{"id":119814,"date":"2024-01-16T14:21:54","date_gmt":"2024-01-16T12:21:54","guid":{"rendered":"https:\/\/elementor.com\/blog\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\/"},"modified":"2025-12-01T09:18:01","modified_gmt":"2025-12-01T07:18:01","slug":"tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023","status":"publish","type":"post","link":"https:\/\/elementor.com\/blog\/it\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\/","title":{"rendered":"Tutte le nuove funzionalit\u00e0 che hai ottenuto nel 2023"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00c8 stato un anno enorme per la comunit\u00e0 di <a class=\"wpil_keyword_link\" href=\"https:\/\/elementor.com\/\" title=\"Elementor\" data-wpil-keyword-link=\"linked\" data-wpil-monitor-id=\"1314\">Elementor<\/a>. Abbiamo rafforzato le fondamenta del nostro plugin e dei siti web ospitati, aggiungendo funzionalit\u00e0 che migliorano i nostri design e flussi di lavoro, migliorando significativamente le prestazioni dei tuoi siti, integrando al contempo la tecnologia AI innovativa direttamente nell&#8217;Editor. <\/p>\n\n<p class=\"wp-block-paragraph\">Questi miglioramenti ti hanno aiutato a costruire il 9,4% di internet con Elementor, rendendo Elementor il plugin WordPress pi\u00f9 popolare.\nQuindi, prima di iniziare il 2024, ricordiamo cosa ha reso il 2023 un grande anno per i Creatori del Web.  <\/p>\n\n<h2 class=\"wp-block-heading\">Prestazioni Migliorate<\/h2>\n\n<p class=\"wp-block-paragraph\">Che tu stia costruendo e gestendo siti web con il nostro plugin o con il <a class=\"wpil_keyword_link\" href=\"https:\/\/elementor.com\/wordpress-hosting\/\" title=\"Elementor Hosting\" data-wpil-keyword-link=\"linked\" data-wpil-monitor-id=\"94\">Elementor Hosting<\/a> Website Builder, sono diventati pi\u00f9 veloci ogni volta che li aggiornavi a una nuova versione di Elementor. <\/p>\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/elementor.com\/blog\/wp-content\/uploads\/2024\/01\/3.png\" alt=\"\" class=\"wp-image-86419\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\">Prestazioni del Plugin <\/h2>\n\n<p class=\"wp-block-paragraph\">Durante l&#8217;ultimo anno, i tuoi core web vital metrics, che misurano i tempi di caricamento del tuo sito, hanno continuato a migliorare.\nUn confronto tra la versione 3.10 e 3.18 ha rivelato un miglioramento del 25% nel Time To First Byte (TTFB) e un miglioramento del 20% nel First Contentful Paint (FCP).\nInoltre, l&#8217;abilitazione di funzionalit\u00e0 come i Flexbox Containers fornisce un ulteriore incremento delle prestazioni.  <\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/elementor.com\/blog\/wp-content\/uploads\/2024\/01\/02-3.png\" alt=\"\" class=\"wp-image-86418\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\">I Siti Web Ospitati da Elementor Sono Pi\u00f9 Veloci che Mai<\/h2>\n\n<p class=\"wp-block-paragraph\">I tuoi siti web Elementor sono ancora pi\u00f9 veloci quando ospitati da noi.\nDurante l&#8217;ultimo anno abbiamo ottimizzato Elementor Hosting per velocit\u00e0 e prestazioni e siamo felici di condividere che i nostri siti web hanno superato la media del settore per un bel po&#8217; di tempo. <\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/elementor.com\/blog\/wp-content\/uploads\/2024\/01\/4-1.png\" alt=\"\" class=\"wp-image-86420\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\">Potenti Funzionalit\u00e0 del Plugin<\/h2>\n\n<p class=\"wp-block-paragraph\">Le prestazioni non erano l&#8217;unica parte del tuo sito web che \u00e8 migliorata.\nDurante il 2023 abbiamo rilasciato 8 nuove versioni del plugin che ti hanno dato nuovi strumenti di design e semplificato il tuo flusso di lavoro.\nLe nuove versioni includevano 41 nuove funzionalit\u00e0 come Elementi Nidificati, Filtro Tassonomia e molto altro ancora.\nHai anche ottenuto 238 miglioramenti alle funzionalit\u00e0 esistenti.\nTutte queste nuove versioni hanno risolto un incredibile 72 delle tue principali richieste su GitHub.     <\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/elementor.com\/blog\/wp-content\/uploads\/2024\/01\/11.png\" alt=\"\" class=\"wp-image-86421\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\">Creazione Alimentata dall&#8217;AI<\/h2>\n\n<p class=\"wp-block-paragraph\">Il 2023 passer\u00e0 alla storia come l&#8217;anno in cui l&#8217;AI generativa \u00e8 entrata nelle nostre vite in innumerevoli campi diversi. <a class=\"wpil_keyword_link\" href=\"https:\/\/elementor.com\/products\/ai\/\" title=\"Elementor AI\" data-wpil-keyword-link=\"linked\" data-wpil-monitor-id=\"2311\">Elementor AI<\/a> ha assicurato che la creazione web fosse uno di questi. Il nostro obiettivo era di potenziarti con strumenti AI che migliorassero il tuo flusso di lavoro, offrendoti nuovi e pi\u00f9 veloci modi per ottenere risultati perfetti al pixel. Le prime funzionalit\u00e0 rilasciate ti permettevano di generare testo, immagini e codice direttamente nel tuo browser. Le versioni successive includevano strumenti di modifica delle immagini come Sostituisci e Rimuovi Sfondo, Genera Variazioni di Immagini, Riempimento Generativo e altro ancora. Poco prima della fine dell&#8217;anno, ora puoi combinare tutte queste funzionalit\u00e0 con layout di contenitori generati dall&#8217;AI. Questa nuova funzionalit\u00e0 alimentata dall&#8217;AI ti permette di generare layout completi di Elementor, inclusi i loro contenuti, con un semplice prompt come &#8220;Crea una pagina <a class=\"wpil_keyword_link\" href=\"https:\/\/elementor.com\/blog\/it\/come-risolvere-lerrore-404-not-found-sul-tuo-sito\/\" title=\"404\" data-wpil-keyword-link=\"linked\" data-wpil-monitor-id=\"4616\">404<\/a> rosa per un negozio di abbigliamento.&#8221; Puoi anche usare contenitori esistenti come riferimento e generare variazioni simili. Inoltre, puoi usare internet aperto come riferimento fornendo a Elementor AI un <a class=\"wpil_keyword_link\" href=\"https:\/\/elementor.com\/blog\/it\/what-is-a-urlstructure-syntax-best-practices\/\" title=\"URL\" data-wpil-keyword-link=\"linked\" data-wpil-monitor-id=\"7140\">URL<\/a>.<\/p>\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/elementor.com\/cdn-cgi\/image\/f=auto,w=840,h=441\/blog\/wp-content\/uploads\/2024\/01\/13-1.png\" alt=\"\" class=\"wp-image-86423\" width=\"840\" height=\"441\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\">Elementor Hosting: La Scelta Migliore per il Tuo Sito Web Elementor<\/h2>\n\n<p class=\"wp-block-paragraph\">Elementor Hosting ha fatto un grande passo avanti nell&#8217;ultimo anno, eguagliando i migliori del settore con funzionalit\u00e0 come staging avanzato e clonazione insieme a strumenti che ti danno il pieno controllo sul tuo sito come SFTP e Accesso al Database.\nHai anche ottenuto il nuovissimo hub aziendale, dove puoi facilmente configurare il tuo dominio e email professionale e garantire una forte presenza online con altri strumenti di branding.\nAbbiamo fatto in modo che ospitare i tuoi siti web Elementor con noi sia pi\u00f9 veloce che altrove.\nCon i nostri plugin accelerati unici, uno strumento di caching integrato e un salto al livello superiore di Google <a class=\"wpil_keyword_link\" href=\"https:\/\/elementor.com\/blog\/it\/10-best-cloud-hosting-for-wordpress-in-year\/\" title=\"10 Best Cloud Hosting for WordPress in 2025\" data-wpil-keyword-link=\"linked\" data-wpil-monitor-id=\"21581\">Cloud<\/a>, i tuoi visitatori noteranno la differenza.   <\/p>\n\n<p class=\"wp-block-paragraph\">Con Elementor Hosting, iniziare sul tuo sito web non \u00e8 mai stato cos\u00ec veloce.\nChe tu stia iniziando da zero, utilizzando i nostri <a class=\"wpil_keyword_link\" href=\"\" title=\"\" data-wpil-keyword-link=\"\" data-wpil-monitor-id=\"\">kits<\/a> o migrando un sito, la configurazione ora \u00e8 una questione di minuti, grazie ai nostri strumenti intuitivi e alla checklist di configurazione.\nInoltre, con funzionalit\u00e0 come lo strumento &#8216;Pagine Recenti&#8217; e miglioramenti continui, stiamo costantemente innovando per migliorare ulteriormente il tuo flusso di lavoro.\nInfine, abbiamo iniziato a offrire piani Multi-Sito completi, un significativo aggiornamento alle nostre soluzioni di hosting, portandoti sia flessibilit\u00e0 che scalabilit\u00e0.   <\/p>\n\n<h2 class=\"wp-block-heading\">Questo \u00e8 tutto per il 2023 &#8211; Avanti con il 2024!<\/h2>\n\n<p class=\"wp-block-paragraph\">L&#8217;ultimo anno \u00e8 stato incredibile per i creatori del web.\nIl plugin ha fatto progressi significativi con 8 nuove versioni, introducendo potenti strumenti di design e capacit\u00e0 per semplificare il tuo flusso di lavoro.\nAbbiamo anche incorporato la rivoluzione dell&#8217;AI nell&#8217;Editor, fornendoti strumenti che erano inimmaginabili solo pochi mesi fa.\nInoltre, abbiamo portato Elementor Hosting a un nuovo livello, superando gli standard del settore con prestazioni fulminee e strumenti di hosting che lo rendono la scelta migliore per ospitare qualsiasi sito web Elementor.\nSiamo entusiasti di continuare questo slancio e portare ancora pi\u00f9 funzionalit\u00e0 potenzianti ai creatori del web nel 2024.    <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Proprio prima di iniziare il 2024, prendiamoci un momento per guardare indietro a tutte le incredibili funzionalit\u00e0 che hai ricevuto durante il 2023 &#8211; inclusi miglioramenti delle prestazioni, potenti strumenti di design, hosting pi\u00f9 veloce e funzionalit\u00e0 AI rivoluzionarie.<\/p>\n","protected":false},"author":162340,"featured_media":119816,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[470,458,463,456],"tags":[474,465,460],"marketing_persona":[],"marketing_intent":[],"class_list":["post-119814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elementor-it","category-elementor-ai-it","category-hosting-it","category-nuove-funzionalita","tag-banner-ai-it","tag-banner-exclude-default-it","tag-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tutte le nuove funzionalit\u00e0 che hai ottenuto nel 2023<\/title>\n<meta name=\"description\" content=\"Proprio prima di iniziare il 2024, prendiamoci un momento per guardare indietro a tutte le incredibili funzionalit\u00e0 che hai ricevuto durante il 2023 - inclusi miglioramenti delle prestazioni, potenti strumenti di design, hosting pi\u00f9 veloce e funzionalit\u00e0 AI rivoluzionarie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elementor.com\/blog\/it\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tutte le nuove funzionalit\u00e0 che hai ottenuto nel 2023\" \/>\n<meta property=\"og:description\" content=\"Proprio prima di iniziare il 2024, prendiamoci un momento per guardare indietro a tutte le incredibili funzionalit\u00e0 che hai ricevuto durante il 2023 - inclusi miglioramenti delle prestazioni, potenti strumenti di design, hosting pi\u00f9 veloce e funzionalit\u00e0 AI rivoluzionarie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elementor.com\/blog\/it\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elemntor\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-16T12:21:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-01T07:18:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elementor.com\/blog\/wp-content\/uploads\/2024\/01\/2023.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Dean Issacharoff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elemntor\" \/>\n<meta name=\"twitter:site\" content=\"@elemntor\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dean Issacharoff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\\\/\"},\"author\":{\"name\":\"Dean Issacharoff\",\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/#\\\/schema\\\/person\\\/c1e360690c573e3e91ec4abdb7541055\"},\"headline\":\"Tutte le nuove funzionalit\u00e0 che hai ottenuto nel 2023\",\"datePublished\":\"2024-01-16T12:21:54+00:00\",\"dateModified\":\"2025-12-01T07:18:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\\\/\"},\"wordCount\":829,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elementor.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/2023.png\",\"keywords\":[\"banner-ai\",\"banner-exclude-default\",\"Video\"],\"articleSection\":[\"Elementor\",\"Elementor AI\",\"Hosting\",\"Nuove Funzionalit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\\\/\",\"url\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\\\/\",\"name\":\"Tutte le nuove funzionalit\u00e0 che hai ottenuto nel 2023\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elementor.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/2023.png\",\"datePublished\":\"2024-01-16T12:21:54+00:00\",\"dateModified\":\"2025-12-01T07:18:01+00:00\",\"description\":\"Proprio prima di iniziare il 2024, prendiamoci un momento per guardare indietro a tutte le incredibili funzionalit\u00e0 che hai ricevuto durante il 2023 - inclusi miglioramenti delle prestazioni, potenti strumenti di design, hosting pi\u00f9 veloce e funzionalit\u00e0 AI rivoluzionarie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elementor.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/2023.png\",\"contentUrl\":\"https:\\\/\\\/elementor.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/2023.png\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elementor\",\"item\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/category\\\/elementor-it\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tutte le nuove funzionalit\u00e0 che hai ottenuto nel 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/\",\"name\":\"Elementor\",\"description\":\"Website Builder for WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/#organization\",\"name\":\"Elementor\",\"url\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elementor.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/images.png\",\"contentUrl\":\"https:\\\/\\\/elementor.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/images.png\",\"width\":225,\"height\":225,\"caption\":\"Elementor\"},\"image\":{\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/elemntor\\\/\",\"https:\\\/\\\/x.com\\\/elemntor\",\"https:\\\/\\\/www.instagram.com\\\/elementor\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCt9kG_EDX8zwGSC1-ycJJVA?sub_confirmation=1\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Elementor\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/#\\\/schema\\\/person\\\/c1e360690c573e3e91ec4abdb7541055\",\"name\":\"Dean Issacharoff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/18b262e140892fa3c934d7d7c4e424d8fff8def6f71a266ab9390bc5478f66a0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/18b262e140892fa3c934d7d7c4e424d8fff8def6f71a266ab9390bc5478f66a0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/18b262e140892fa3c934d7d7c4e424d8fff8def6f71a266ab9390bc5478f66a0?s=96&d=mm&r=g\",\"caption\":\"Dean Issacharoff\"},\"description\":\"Dean is a Product Marketing Manager at Elementor with years of experience in marketing and strategic communications. He loves good books, bad movies, and cooking for friends.\",\"url\":\"https:\\\/\\\/elementor.com\\\/blog\\\/it\\\/author\\\/deanissach\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tutte le nuove funzionalit\u00e0 che hai ottenuto nel 2023","description":"Proprio prima di iniziare il 2024, prendiamoci un momento per guardare indietro a tutte le incredibili funzionalit\u00e0 che hai ricevuto durante il 2023 - inclusi miglioramenti delle prestazioni, potenti strumenti di design, hosting pi\u00f9 veloce e funzionalit\u00e0 AI rivoluzionarie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elementor.com\/blog\/it\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\/","og_locale":"it_IT","og_type":"article","og_title":"Tutte le nuove funzionalit\u00e0 che hai ottenuto nel 2023","og_description":"Proprio prima di iniziare il 2024, prendiamoci un momento per guardare indietro a tutte le incredibili funzionalit\u00e0 che hai ricevuto durante il 2023 - inclusi miglioramenti delle prestazioni, potenti strumenti di design, hosting pi\u00f9 veloce e funzionalit\u00e0 AI rivoluzionarie.","og_url":"https:\/\/elementor.com\/blog\/it\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\/","og_site_name":"Blog","article_publisher":"https:\/\/www.facebook.com\/elemntor\/","article_published_time":"2024-01-16T12:21:54+00:00","article_modified_time":"2025-12-01T07:18:01+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/elementor.com\/blog\/wp-content\/uploads\/2024\/01\/2023.png","type":"image\/png"}],"author":"Dean Issacharoff","twitter_card":"summary_large_image","twitter_creator":"@elemntor","twitter_site":"@elemntor","twitter_misc":{"Scritto da":"Dean Issacharoff","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elementor.com\/blog\/it\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\/#article","isPartOf":{"@id":"https:\/\/elementor.com\/blog\/it\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\/"},"author":{"name":"Dean Issacharoff","@id":"https:\/\/elementor.com\/blog\/it\/#\/schema\/person\/c1e360690c573e3e91ec4abdb7541055"},"headline":"Tutte le nuove funzionalit\u00e0 che hai ottenuto nel 2023","datePublished":"2024-01-16T12:21:54+00:00","dateModified":"2025-12-01T07:18:01+00:00","mainEntityOfPage":{"@id":"https:\/\/elementor.com\/blog\/it\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\/"},"wordCount":829,"commentCount":0,"publisher":{"@id":"https:\/\/elementor.com\/blog\/it\/#organization"},"image":{"@id":"https:\/\/elementor.com\/blog\/it\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/elementor.com\/blog\/wp-content\/uploads\/2024\/01\/2023.png","keywords":["banner-ai","banner-exclude-default","Video"],"articleSection":["Elementor","Elementor AI","Hosting","Nuove Funzionalit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/elementor.com\/blog\/it\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\/","url":"https:\/\/elementor.com\/blog\/it\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\/","name":"Tutte le nuove funzionalit\u00e0 che hai ottenuto nel 2023","isPartOf":{"@id":"https:\/\/elementor.com\/blog\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elementor.com\/blog\/it\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\/#primaryimage"},"image":{"@id":"https:\/\/elementor.com\/blog\/it\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/elementor.com\/blog\/wp-content\/uploads\/2024\/01\/2023.png","datePublished":"2024-01-16T12:21:54+00:00","dateModified":"2025-12-01T07:18:01+00:00","description":"Proprio prima di iniziare il 2024, prendiamoci un momento per guardare indietro a tutte le incredibili funzionalit\u00e0 che hai ricevuto durante il 2023 - inclusi miglioramenti delle prestazioni, potenti strumenti di design, hosting pi\u00f9 veloce e funzionalit\u00e0 AI rivoluzionarie.","breadcrumb":{"@id":"https:\/\/elementor.com\/blog\/it\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elementor.com\/blog\/it\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/elementor.com\/blog\/it\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\/#primaryimage","url":"https:\/\/elementor.com\/blog\/wp-content\/uploads\/2024\/01\/2023.png","contentUrl":"https:\/\/elementor.com\/blog\/wp-content\/uploads\/2024\/01\/2023.png","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/elementor.com\/blog\/it\/tutte-le-nuove-funzionalita-che-hai-ottenuto-nel-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/elementor.com\/blog\/it\/"},{"@type":"ListItem","position":2,"name":"Elementor","item":"https:\/\/elementor.com\/blog\/it\/category\/elementor-it\/"},{"@type":"ListItem","position":3,"name":"Tutte le nuove funzionalit\u00e0 che hai ottenuto nel 2023"}]},{"@type":"WebSite","@id":"https:\/\/elementor.com\/blog\/it\/#website","url":"https:\/\/elementor.com\/blog\/it\/","name":"Elementor","description":"Website Builder for WordPress","publisher":{"@id":"https:\/\/elementor.com\/blog\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elementor.com\/blog\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/elementor.com\/blog\/it\/#organization","name":"Elementor","url":"https:\/\/elementor.com\/blog\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/elementor.com\/blog\/it\/#\/schema\/logo\/image\/","url":"https:\/\/elementor.com\/blog\/wp-content\/uploads\/2025\/06\/images.png","contentUrl":"https:\/\/elementor.com\/blog\/wp-content\/uploads\/2025\/06\/images.png","width":225,"height":225,"caption":"Elementor"},"image":{"@id":"https:\/\/elementor.com\/blog\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elemntor\/","https:\/\/x.com\/elemntor","https:\/\/www.instagram.com\/elementor\/","https:\/\/www.youtube.com\/channel\/UCt9kG_EDX8zwGSC1-ycJJVA?sub_confirmation=1","https:\/\/en.wikipedia.org\/wiki\/Elementor"]},{"@type":"Person","@id":"https:\/\/elementor.com\/blog\/it\/#\/schema\/person\/c1e360690c573e3e91ec4abdb7541055","name":"Dean Issacharoff","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/18b262e140892fa3c934d7d7c4e424d8fff8def6f71a266ab9390bc5478f66a0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/18b262e140892fa3c934d7d7c4e424d8fff8def6f71a266ab9390bc5478f66a0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/18b262e140892fa3c934d7d7c4e424d8fff8def6f71a266ab9390bc5478f66a0?s=96&d=mm&r=g","caption":"Dean Issacharoff"},"description":"Dean is a Product Marketing Manager at Elementor with years of experience in marketing and strategic communications. He loves good books, bad movies, and cooking for friends.","url":"https:\/\/elementor.com\/blog\/it\/author\/deanissach\/"}]}},"_links":{"self":[{"href":"https:\/\/elementor.com\/blog\/it\/wp-json\/wp\/v2\/posts\/119814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elementor.com\/blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elementor.com\/blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elementor.com\/blog\/it\/wp-json\/wp\/v2\/users\/162340"}],"replies":[{"embeddable":true,"href":"https:\/\/elementor.com\/blog\/it\/wp-json\/wp\/v2\/comments?post=119814"}],"version-history":[{"count":0,"href":"https:\/\/elementor.com\/blog\/it\/wp-json\/wp\/v2\/posts\/119814\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elementor.com\/blog\/it\/wp-json\/wp\/v2\/media\/119816"}],"wp:attachment":[{"href":"https:\/\/elementor.com\/blog\/it\/wp-json\/wp\/v2\/media?parent=119814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elementor.com\/blog\/it\/wp-json\/wp\/v2\/categories?post=119814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elementor.com\/blog\/it\/wp-json\/wp\/v2\/tags?post=119814"},{"taxonomy":"marketing_persona","embeddable":true,"href":"https:\/\/elementor.com\/blog\/it\/wp-json\/wp\/v2\/marketing_persona?post=119814"},{"taxonomy":"marketing_intent","embeddable":true,"href":"https:\/\/elementor.com\/blog\/it\/wp-json\/wp\/v2\/marketing_intent?post=119814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}