{"id":112021,"date":"2024-07-24T10:13:54","date_gmt":"2024-07-24T07:13:54","guid":{"rendered":"https:\/\/elementor.com\/blog\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\/"},"modified":"2025-11-29T19:32:18","modified_gmt":"2025-11-29T17:32:18","slug":"presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas","status":"publish","type":"post","link":"https:\/\/elementor.com\/blog\/es\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\/","title":{"rendered":"Presentando Elementor 3.23: Resultados en Vivo, Botones Flotantes, Enlace en Bio &amp; m\u00e1s!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Elementor 3.23 est\u00e1 aqu\u00ed, trayendo una serie de nuevas caracter\u00edsticas y mejoras dise\u00f1adas para elevar el rendimiento, la accesibilidad y las capacidades de dise\u00f1o de tu sitio web.\nDesde un widget de B\u00fasqueda mejorado hasta vers\u00e1tiles Botones Flotantes y nuevos widgets de Enlace en Bio, esta actualizaci\u00f3n te permite crear sitios web m\u00e1s atractivos y eficientes. <\/p>\n\n<h2 class=\"wp-block-heading\">[Pro] Nuevo Widget de B\u00fasqueda que Proporciona Resultados en Tiempo Real con AJAX<\/h2>\n\n<p class=\"wp-block-paragraph\">El nuevo Widget de B\u00fasqueda de Elementor ahora utiliza AJAX para mostrar resultados en vivo mientras los visitantes escriben, eliminando la necesidad de navegar a una p\u00e1gina de resultados separada.\nLa capacidad de b\u00fasqueda en tiempo real fue una de las caracter\u00edsticas m\u00e1s solicitadas, y asegura que los visitantes obtengan retroalimentaci\u00f3n instant\u00e1nea, mejorando su experiencia de navegaci\u00f3n.\nLos resultados en vivo se muestran en un formato de bucle, apareciendo como un cuadro desplegable debajo de la barra de b\u00fasqueda mientras se escribe.\nEsta caracter\u00edstica mejora significativamente el descubrimiento de contenido y la experiencia del visitante.   <\/p>\n\n<h3 class=\"wp-block-heading\">Experiencia de B\u00fasqueda Personalizable<\/h3>\n\n<p class=\"wp-block-paragraph\">Puedes personalizar todo, desde el campo de entrada de b\u00fasqueda y los botones de env\u00edo hasta el formato de la cuadr\u00edcula de bucle de los resultados en vivo.\nAjusta el texto del marcador de posici\u00f3n, los \u00edconos y los campos de env\u00edo para que coincidan con el dise\u00f1o de tu sitio.\nAdem\u00e1s, puedes controlar c\u00f3mo interact\u00faan los visitantes con la funci\u00f3n de b\u00fasqueda, como presionar Enter, hacer clic en el bot\u00f3n de b\u00fasqueda, o ambos.\nLas opciones de control de contenido del widget y de filtrado din\u00e1mico permiten una experiencia de b\u00fasqueda altamente personalizada.   <\/p>\n\n<h3 class=\"wp-block-heading\">Ayuda a los Visitantes a Encontrar lo que Est\u00e1n Buscando<\/h3>\n\n<p class=\"wp-block-paragraph\">Navegar a la Pesta\u00f1a de Contenido y activar los resultados en vivo en la Secci\u00f3n de Resultados es sencillo.\nElige qu\u00e9 Plantilla de Bucle deseas para tus resultados en vivo o crea una nueva desde el Constructor de Temas.\nPersonaliza el dise\u00f1o del cuadro desplegable configurando el n\u00famero de columnas y de elementos de resultado que se mostrar\u00e1n a la vez.\nTambi\u00e9n puedes establecer el n\u00famero m\u00ednimo de caracteres requeridos antes de que comiencen a aparecer los resultados en vivo y personalizar el mensaje de \u00abnada encontrado\u00bb.\nUsar Consulta es esencial cuando deseas filtrar los resultados, facilitando que los visitantes encuentren exactamente lo que est\u00e1n buscando.    <\/p>\n\n<p class=\"wp-block-paragraph\">Esta caracter\u00edstica est\u00e1 activa por defecto en todos los nuevos sitios web.\nEn un sitio web existente, act\u00edvala navegando al Panel de Control de WordPress \u2192 Elementor \u2192 Caracter\u00edsticas \u2192 activar \u201cB\u00fasqueda\u201d. <\/p>\n\n<p class=\"read-more-link show-free wp-block-paragraph\"><a href=\"https:\/\/elementor.com\/pricing\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/elementor.com\/pricing\/\">Obtener Elementor Pro<\/a><\/p>\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/elementor.com\/cdn-cgi\/image\/f=auto,w=1024,h=1024\/blog\/wp-content\/uploads\/2024\/07\/Search-min-1024x538.png\" alt=\"\" class=\"wp-image-96138\" srcset=\"https:\/\/elementor.com\/cdn-cgi\/image\/f=auto,w=1024\/blog\/wp-content\/uploads\/2024\/07\/Search-min-1024x538.png 1024w, https:\/\/elementor.com\/cdn-cgi\/image\/f=auto,w=300\/blog\/wp-content\/uploads\/2024\/07\/Search-min-300x158.png 300w, https:\/\/elementor.com\/cdn-cgi\/image\/f=auto,w=768\/blog\/wp-content\/uploads\/2024\/07\/Search-min-768x403.png 768w, https:\/\/elementor.com\/cdn-cgi\/image\/f=auto,w=1200\/blog\/wp-content\/uploads\/2024\/07\/Search-min.png 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\">Botones Flotantes: Aumenta la Conversi\u00f3n y el Compromiso<\/h2>\n\n<p class=\"wp-block-paragraph\">El nuevo widget de Bot\u00f3n Flotante es perfecto para aumentar las conversiones al enlazar directamente a chats u otras plataformas.\nYa sea que necesites un bot\u00f3n de WhatsApp para iniciar una conversaci\u00f3n, un bot\u00f3n de contacto con m\u00faltiples enlaces, o un bot\u00f3n de informaci\u00f3n con detalles clave, esta caracter\u00edstica proporciona una soluci\u00f3n vers\u00e1til.\nPuedes agregar estos botones navegando al Panel de Control de WordPress \u2192 Plantillas \u2192 Botones Flotantes.\nHaz clic en Agregar Nuevo Bot\u00f3n Flotante y elige una plantilla pre-dise\u00f1ada personalizable para comenzar.   <\/p>\n\n<p class=\"wp-block-paragraph\">Obtendr\u00e1s tres plantillas dise\u00f1adas profesionalmente con la versi\u00f3n gratuita de Elementor, y m\u00e1s de 40 plantillas con Elementor Pro.<\/p>\n\n<h3 class=\"wp-block-heading\">Opciones de Contacto Vers\u00e1tiles<\/h3>\n\n<p class=\"wp-block-paragraph\">Cada plantilla puede ser adaptada seg\u00fan el contenido que incluye.\nPor ejemplo, si est\u00e1s usando una plantilla de Chat \u00danico, puedes elegir plataformas de mensajer\u00eda como WhatsApp, Messenger, SMS, Email, y m\u00e1s.\nLuego, ingresa tu informaci\u00f3n como n\u00famero de tel\u00e9fono o correo electr\u00f3nico para asegurar que los visitantes puedan ponerse en contacto.\nDentro de cada Bot\u00f3n Flotante, puedes personalizar el avatar y el mensaje de chat para personalizar la interacci\u00f3n del visitante.   <\/p>\n\n<h3 class=\"wp-block-heading\">Hazlo Tuyo<\/h3>\n\n<p class=\"wp-block-paragraph\">Puedes dise\u00f1ar y mantener la consistencia de la marca ajustando los diversos elementos usando la secci\u00f3n de Estilo, as\u00ed como controlar y personalizar las animaciones de entrada y salida del Bot\u00f3n Flotante.\nTambi\u00e9n puedes personalizar la ubicaci\u00f3n del bot\u00f3n desde la Pesta\u00f1a Avanzada, permitiendo que se convierta en un componente prominente del dise\u00f1o de tu sitio web. <\/p>\n\n<p class=\"wp-block-paragraph\">El seguimiento de clics es otra herramienta \u00fatil que te ayuda a monitorear el impacto de tu nuevo Bot\u00f3n Flotante.\nPuedes ver el seguimiento de clics en tu lista de Botones Flotantes (panel de control de WordPress \u2192 Plantillas \u2192 Botones Flotantes). <\/p>\n\n<h3 class=\"wp-block-heading\">Aumenta el Compromiso &amp; la Conversi\u00f3n con Condiciones de Visualizaci\u00f3n<\/h3>\n\n<p class=\"wp-block-paragraph\">Usando Elementor Pro, puedes establecer Condiciones de Visualizaci\u00f3n para controlar cu\u00e1ndo, d\u00f3nde y a qui\u00e9n aparecen los Botones Flotantes.\nLas condiciones de visualizaci\u00f3n te permiten dirigirte a segmentos espec\u00edficos de audiencia, asegurando que los Botones Flotantes se muestren solo a los visitantes relevantes.\nPor ejemplo, puedes incluir un bot\u00f3n de chat en todas las p\u00e1ginas, o establecer diferentes botones de chat para las diferentes p\u00e1ginas.\nTambi\u00e9n puedes controlar la apariencia del bot\u00f3n seg\u00fan el recorrido del visitante.\nPor ejemplo, un bot\u00f3n de chat puede mostrarse en las p\u00e1ginas de productos para responder consultas de los clientes sobre los productos, mientras que un bot\u00f3n diferente puede aparecer en la p\u00e1gina de pago para soporte r\u00e1pido y un empuje hacia la conversi\u00f3n.    <\/p>\n\n<p class=\"wp-block-paragraph\">Esta caracter\u00edstica est\u00e1 ahora activa por defecto en los nuevos sitios web.\nEn un sitio web existente, act\u00edvala navegando al Panel de Control de WordPress \u2192 Elementor \u2192 Caracter\u00edsticas \u2192 activar \u201cBotones Flotantes\u201d. <\/p>\n\n<p class=\"read-more-link wp-block-paragraph\"><a href=\"https:\/\/elementor.com\/features\/contact-button\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/elementor.com\/features\/contact-button\/\">Aprende m\u00e1s<\/a><\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/elementor.com\/cdn-cgi\/image\/f=auto,w=1024,h=1024\/blog\/wp-content\/uploads\/2024\/07\/Floating-Buttons-min-1024x538.png\" alt=\"\" class=\"wp-image-96141\" srcset=\"https:\/\/elementor.com\/cdn-cgi\/image\/f=auto,w=1024\/blog\/wp-content\/uploads\/2024\/07\/Floating-Buttons-min-1024x538.png 1024w, https:\/\/elementor.com\/cdn-cgi\/image\/f=auto,w=300\/blog\/wp-content\/uploads\/2024\/07\/Floating-Buttons-min-300x158.png 300w, https:\/\/elementor.com\/cdn-cgi\/image\/f=auto,w=768\/blog\/wp-content\/uploads\/2024\/07\/Floating-Buttons-min-768x403.png 768w, https:\/\/elementor.com\/cdn-cgi\/image\/f=auto,w=1200\/blog\/wp-content\/uploads\/2024\/07\/Floating-Buttons-min.png 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\">Widgets de Enlace en Bio: Muestra tus Enlaces sin Esfuerzo<\/h2>\n\n<p class=\"wp-block-paragraph\">Dado que las plataformas de redes sociales limitan la cantidad de enlaces que puedes agregar en tu biograf\u00eda, agregar una p\u00e1gina web que consolide contenido, CTAs y otros enlaces se convirti\u00f3 en una pr\u00e1ctica popular, llevando a la creaci\u00f3n de varias herramientas de Enlace en Bio.<\/p>\n\n<h3 class=\"wp-block-heading\">\u00a17 Nuevos Widgets de Enlace en Bio!<\/h3>\n\n<p class=\"wp-block-paragraph\">La versi\u00f3n 3.23 de Elementor introduce siete widgets de Link in Bio listos para usar, ideales para crear p\u00e1ginas responsivas que alberguen todos tus enlaces importantes.\nEstos widgets son perfectos para plataformas sociales como Instagram, <a class=\"wpil_keyword_link\" href=\"https:\/\/elementor.com\/blog\/tiktok\/\" title=\"The Best Time to Post on TikTok in 2025\" data-wpil-keyword-link=\"linked\" data-wpil-monitor-id=\"23872\">TikTok<\/a>, YouTube, X (anteriormente Twitter), LinkedIn y m\u00e1s, ayudando a dirigir tr\u00e1fico a tu trabajo, marca o negocio con facilidad.\nCada widget est\u00e1 construido de manera diferente para adaptarse a tus necesidades, como promover plataformas externas, organizar tus enlaces de contacto o mostrar tu trabajo.  <\/p>\n\n<h3 class=\"wp-block-heading\">Listo con solo unos clics<\/h3>\n\n<p class=\"wp-block-paragraph\">Puedes encontrar los siete nuevos widgets en una nueva secci\u00f3n de widgets dentro del Editor, llamada \u201cLink in Bio\u201d.\nUna vez que hayas elegido un widget, puedes actualizar su contenido para adaptarlo a la est\u00e9tica de tu marca.\nCon m\u00e1s de 60 bloques bellamente dise\u00f1ados disponibles en la biblioteca de plantillas, puedes construir r\u00e1pidamente una p\u00e1gina que se ajuste al estilo y necesidades de tu marca.  <\/p>\n\n<p class=\"wp-block-paragraph\">Los widgets est\u00e1n dise\u00f1ados para la simplicidad, permiti\u00e9ndote personalizar r\u00e1pidamente im\u00e1genes, texto, enlaces, \u00edconos y dise\u00f1o para reflejar la identidad de tu marca.\nYa sea que elijas un bloque pre-dise\u00f1ado de la biblioteca o crees el tuyo propio, el proceso es intuitivo y eficiente.\nEl widget de Link in Bio \u201cMinimalista\u201d est\u00e1 disponible para todos los que crean con Elementor, mientras que los usuarios de Elementor Pro tienen acceso a los siete widgets, asegurando un conjunto de herramientas completo para cualquier proyecto.  <\/p>\n\n<p class=\"wp-block-paragraph\">Esta funci\u00f3n ahora est\u00e1 activa por defecto en los nuevos sitios web.\nEn un sitio web existente, act\u00edvala navegando al Panel de WordPress \u2192 Elementor \u2192 Funciones \u2192 activar \u201cLink In Bio\u201d. <\/p>\n\n<p class=\"read-more-link wp-block-paragraph\"><a href=\"https:\/\/elementor.com\/features\/link-in-bio\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/elementor.com\/features\/link-in-bio\/\">Aprender m\u00e1s<\/a><\/p>\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/elementor.com\/features\/link-in-bio\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/elementor.com\/cdn-cgi\/image\/f=auto,w=1024,h=1024\/blog\/wp-content\/uploads\/2024\/07\/Link-in-Bio-min-1024x538.png\" alt=\"\" class=\"wp-image-96142\" srcset=\"https:\/\/elementor.com\/cdn-cgi\/image\/f=auto,w=1024\/blog\/wp-content\/uploads\/2024\/07\/Link-in-Bio-min-1024x538.png 1024w, https:\/\/elementor.com\/cdn-cgi\/image\/f=auto,w=300\/blog\/wp-content\/uploads\/2024\/07\/Link-in-Bio-min-300x158.png 300w, https:\/\/elementor.com\/cdn-cgi\/image\/f=auto,w=768\/blog\/wp-content\/uploads\/2024\/07\/Link-in-Bio-min-768x403.png 768w, https:\/\/elementor.com\/cdn-cgi\/image\/f=auto,w=1200\/blog\/wp-content\/uploads\/2024\/07\/Link-in-Bio-min.png 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n<h2 class=\"wp-block-heading\">Elementos Anidados: Dise\u00f1os Avanzados con Rendimiento Mejorado<\/h2>\n\n<p class=\"wp-block-paragraph\">En la versi\u00f3n 3.10, introdujimos Elementos Anidados, lo que te permite dise\u00f1ar de manera m\u00e1s flexible.\nUtilizando Contenedores Flexbox, los Elementos Anidados te permiten anidar cualquier elemento dentro de otro.\nEsto te permite crear dise\u00f1os de sitios web m\u00e1s complejos y sofisticados.\nSin embargo, algunos usuarios experimentaron un rendimiento lento del Editor mientras trabajaban en estos elementos.   <\/p>\n\n<p class=\"wp-block-paragraph\">Se han implementado mejoras significativas en el rendimiento en la versi\u00f3n 3.23 para mejorar esto, y la infraestructura del widget se ha actualizado para que los cambios solo afecten al elemento espec\u00edfico y no requieran cargar todo el widget.\nEsta optimizaci\u00f3n mejora el tiempo de interacci\u00f3n del Editor en un 60%-98%, permiti\u00e9ndote crear dise\u00f1os intrincados m\u00e1s r\u00e1pido, asegurando una experiencia de edici\u00f3n fluida. <\/p>\n\n<p class=\"wp-block-paragraph\">Para activar Elementos Anidados, navega al Panel de WordPress \u2192 Elementor \u2192 Funciones \u2192 activar \u201cElementos Anidados\u201d.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/elementor.com\/cdn-cgi\/image\/f=auto,w=1024,h=1024\/blog\/wp-content\/uploads\/2024\/07\/Nested-Elements-Performance-Improvements-min-1024x538.png\" alt=\"\" class=\"wp-image-96144\" srcset=\"https:\/\/elementor.com\/cdn-cgi\/image\/f=auto,w=1024\/blog\/wp-content\/uploads\/2024\/07\/Nested-Elements-Performance-Improvements-min-1024x538.png 1024w, https:\/\/elementor.com\/cdn-cgi\/image\/f=auto,w=300\/blog\/wp-content\/uploads\/2024\/07\/Nested-Elements-Performance-Improvements-min-300x158.png 300w, https:\/\/elementor.com\/cdn-cgi\/image\/f=auto,w=768\/blog\/wp-content\/uploads\/2024\/07\/Nested-Elements-Performance-Improvements-min-768x403.png 768w, https:\/\/elementor.com\/cdn-cgi\/image\/f=auto,w=1200\/blog\/wp-content\/uploads\/2024\/07\/Nested-Elements-Performance-Improvements-min.png 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\">Actualizaciones de Funciones y Experimentos<\/h2>\n\n<ul class=\"wp-block-list\">\n<li>Cach\u00e9 de Elementos: Ahora activo por defecto para nuevos sitios, el Cach\u00e9 de Elementos mejora significativamente el rendimiento, reduciendo los tiempos de carga y mejorando la experiencia del visitante.<\/li>\n\n\n\n<li>Barra Superior: Ahora una parte nativa del Editor, la Barra Superior mejora la navegaci\u00f3n y la eficiencia del flujo de trabajo.\nPrevisualiza instant\u00e1neamente vistas responsivas, accede al Constructor de Temas y navega entre p\u00e1ginas con facilidad. <\/li>\n\n\n\n<li>Mejoras de Accesibilidad: Salida de DOM reestructurada &#8211; haciendo que el contenido del Mega Men\u00fa sea completamente accesible para lectores de pantalla.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">Elementor 3.23: Un Paso Adelante en el Dise\u00f1o Web<\/h2>\n\n<p class=\"wp-block-paragraph\">Elementor 3.23 es una actualizaci\u00f3n integral que mejora la exploraci\u00f3n del sitio, la precisi\u00f3n del dise\u00f1o y la experiencia general del visitante.\nCon nuevas herramientas poderosas y mejoras significativas en rendimiento y accesibilidad, esta versi\u00f3n te ayuda a crear sitios web m\u00e1s r\u00e1pidos, inclusivos y atractivos.\nActualiza hoy y lleva tu dise\u00f1o web al siguiente nivel.  <\/p>\n\n<p class=\"read-more-link show-core wp-block-paragraph\"><a href=\"https:\/\/elementor.com\/pricing\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/elementor.com\/pricing\/\">Obtener Elementor Pro<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una actualizaci\u00f3n emocionante: Mejorando el Rendimiento, la Accesibilidad y el Dise\u00f1o con el nuevo widget de B\u00fasqueda, Botones Flotantes, 7 widgets de Enlace en Bio, \u00a1y m\u00e1s!<\/p>\n","protected":false},"author":2024242,"featured_media":112022,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[293,325],"tags":[431],"marketing_persona":[],"marketing_intent":[],"class_list":["post-112021","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elementor-es","category-new-features-es","tag-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentando Elementor 3.23: Resultados en Vivo, Botones Flotantes, Enlace en Bio &amp; m\u00e1s!<\/title>\n<meta name=\"description\" content=\"Una actualizaci\u00f3n emocionante: Mejorando el Rendimiento, la Accesibilidad y el Dise\u00f1o con el nuevo widget de B\u00fasqueda, Botones Flotantes, 7 widgets de Enlace en Bio, \u00a1y m\u00e1s!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elementor.com\/blog\/es\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentando Elementor 3.23: Resultados en Vivo, Botones Flotantes, Enlace en Bio &amp; m\u00e1s!\" \/>\n<meta property=\"og:description\" content=\"Una actualizaci\u00f3n emocionante: Mejorando el Rendimiento, la Accesibilidad y el Dise\u00f1o con el nuevo widget de B\u00fasqueda, Botones Flotantes, 7 widgets de Enlace en Bio, \u00a1y m\u00e1s!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elementor.com\/blog\/es\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elemntor\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-24T07:13:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-29T17:32:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elementor.com\/blog\/wp-content\/uploads\/2024\/07\/323-cover-min.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Roi Tal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elemntor\" \/>\n<meta name=\"twitter:site\" content=\"@elemntor\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roi Tal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\\\/\"},\"author\":{\"name\":\"Roi Tal\",\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/#\\\/schema\\\/person\\\/09f7425d5f0e4e8ac7764b202c165fc0\"},\"headline\":\"Presentando Elementor 3.23: Resultados en Vivo, Botones Flotantes, Enlace en Bio &amp; m\u00e1s!\",\"datePublished\":\"2024-07-24T07:13:54+00:00\",\"dateModified\":\"2025-11-29T17:32:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\\\/\"},\"wordCount\":1648,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elementor.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/323-cover-min.png\",\"keywords\":[\"Video\"],\"articleSection\":[\"Elementor\",\"Nuevas caracter\u00edsticas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\\\/\",\"url\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\\\/\",\"name\":\"Presentando Elementor 3.23: Resultados en Vivo, Botones Flotantes, Enlace en Bio &amp; m\u00e1s!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elementor.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/323-cover-min.png\",\"datePublished\":\"2024-07-24T07:13:54+00:00\",\"dateModified\":\"2025-11-29T17:32:18+00:00\",\"description\":\"Una actualizaci\u00f3n emocionante: Mejorando el Rendimiento, la Accesibilidad y el Dise\u00f1o con el nuevo widget de B\u00fasqueda, Botones Flotantes, 7 widgets de Enlace en Bio, \u00a1y m\u00e1s!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elementor.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/323-cover-min.png\",\"contentUrl\":\"https:\\\/\\\/elementor.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/323-cover-min.png\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elementor\",\"item\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/category\\\/elementor-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Presentando Elementor 3.23: Resultados en Vivo, Botones Flotantes, Enlace en Bio &amp; m\u00e1s!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/\",\"name\":\"Elementor\",\"description\":\"Website Builder for WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/#organization\",\"name\":\"Elementor\",\"url\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elementor.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/images.png\",\"contentUrl\":\"https:\\\/\\\/elementor.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/images.png\",\"width\":225,\"height\":225,\"caption\":\"Elementor\"},\"image\":{\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/elemntor\\\/\",\"https:\\\/\\\/x.com\\\/elemntor\",\"https:\\\/\\\/www.instagram.com\\\/elementor\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCt9kG_EDX8zwGSC1-ycJJVA?sub_confirmation=1\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Elementor\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/#\\\/schema\\\/person\\\/09f7425d5f0e4e8ac7764b202c165fc0\",\"name\":\"Roi Tal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/53a4b8103bf51815f66eec9532fb9ba89fb71bfb887c67660c39f06e73f509a5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/53a4b8103bf51815f66eec9532fb9ba89fb71bfb887c67660c39f06e73f509a5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/53a4b8103bf51815f66eec9532fb9ba89fb71bfb887c67660c39f06e73f509a5?s=96&d=mm&r=g\",\"caption\":\"Roi Tal\"},\"description\":\"Roi is a Product Marketing Manager at Elementor, working in the Editor Plugin team. He comes from a background of music and experience in content marketing and broadcasting, taking pride in creating meaningful communications that evoke and inspire. In his spare time, Roi enjoys making music, cooking, and watching movies.\",\"url\":\"https:\\\/\\\/elementor.com\\\/blog\\\/es\\\/author\\\/roit\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentando Elementor 3.23: Resultados en Vivo, Botones Flotantes, Enlace en Bio &amp; m\u00e1s!","description":"Una actualizaci\u00f3n emocionante: Mejorando el Rendimiento, la Accesibilidad y el Dise\u00f1o con el nuevo widget de B\u00fasqueda, Botones Flotantes, 7 widgets de Enlace en Bio, \u00a1y m\u00e1s!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elementor.com\/blog\/es\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\/","og_locale":"es_ES","og_type":"article","og_title":"Presentando Elementor 3.23: Resultados en Vivo, Botones Flotantes, Enlace en Bio &amp; m\u00e1s!","og_description":"Una actualizaci\u00f3n emocionante: Mejorando el Rendimiento, la Accesibilidad y el Dise\u00f1o con el nuevo widget de B\u00fasqueda, Botones Flotantes, 7 widgets de Enlace en Bio, \u00a1y m\u00e1s!","og_url":"https:\/\/elementor.com\/blog\/es\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\/","og_site_name":"Blog","article_publisher":"https:\/\/www.facebook.com\/elemntor\/","article_published_time":"2024-07-24T07:13:54+00:00","article_modified_time":"2025-11-29T17:32:18+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/elementor.com\/blog\/wp-content\/uploads\/2024\/07\/323-cover-min.png","type":"image\/png"}],"author":"Roi Tal","twitter_card":"summary_large_image","twitter_creator":"@elemntor","twitter_site":"@elemntor","twitter_misc":{"Escrito por":"Roi Tal","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elementor.com\/blog\/es\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\/#article","isPartOf":{"@id":"https:\/\/elementor.com\/blog\/es\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\/"},"author":{"name":"Roi Tal","@id":"https:\/\/elementor.com\/blog\/es\/#\/schema\/person\/09f7425d5f0e4e8ac7764b202c165fc0"},"headline":"Presentando Elementor 3.23: Resultados en Vivo, Botones Flotantes, Enlace en Bio &amp; m\u00e1s!","datePublished":"2024-07-24T07:13:54+00:00","dateModified":"2025-11-29T17:32:18+00:00","mainEntityOfPage":{"@id":"https:\/\/elementor.com\/blog\/es\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\/"},"wordCount":1648,"commentCount":0,"publisher":{"@id":"https:\/\/elementor.com\/blog\/es\/#organization"},"image":{"@id":"https:\/\/elementor.com\/blog\/es\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\/#primaryimage"},"thumbnailUrl":"https:\/\/elementor.com\/blog\/wp-content\/uploads\/2024\/07\/323-cover-min.png","keywords":["Video"],"articleSection":["Elementor","Nuevas caracter\u00edsticas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/elementor.com\/blog\/es\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\/","url":"https:\/\/elementor.com\/blog\/es\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\/","name":"Presentando Elementor 3.23: Resultados en Vivo, Botones Flotantes, Enlace en Bio &amp; m\u00e1s!","isPartOf":{"@id":"https:\/\/elementor.com\/blog\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elementor.com\/blog\/es\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\/#primaryimage"},"image":{"@id":"https:\/\/elementor.com\/blog\/es\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\/#primaryimage"},"thumbnailUrl":"https:\/\/elementor.com\/blog\/wp-content\/uploads\/2024\/07\/323-cover-min.png","datePublished":"2024-07-24T07:13:54+00:00","dateModified":"2025-11-29T17:32:18+00:00","description":"Una actualizaci\u00f3n emocionante: Mejorando el Rendimiento, la Accesibilidad y el Dise\u00f1o con el nuevo widget de B\u00fasqueda, Botones Flotantes, 7 widgets de Enlace en Bio, \u00a1y m\u00e1s!","breadcrumb":{"@id":"https:\/\/elementor.com\/blog\/es\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elementor.com\/blog\/es\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elementor.com\/blog\/es\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\/#primaryimage","url":"https:\/\/elementor.com\/blog\/wp-content\/uploads\/2024\/07\/323-cover-min.png","contentUrl":"https:\/\/elementor.com\/blog\/wp-content\/uploads\/2024\/07\/323-cover-min.png","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/elementor.com\/blog\/es\/presentando-elementor-3-23-resultados-en-vivo-botones-flotantes-enlace-en-bio-mas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/elementor.com\/blog\/es\/"},{"@type":"ListItem","position":2,"name":"Elementor","item":"https:\/\/elementor.com\/blog\/es\/category\/elementor-es\/"},{"@type":"ListItem","position":3,"name":"Presentando Elementor 3.23: Resultados en Vivo, Botones Flotantes, Enlace en Bio &amp; m\u00e1s!"}]},{"@type":"WebSite","@id":"https:\/\/elementor.com\/blog\/es\/#website","url":"https:\/\/elementor.com\/blog\/es\/","name":"Elementor","description":"Website Builder for WordPress","publisher":{"@id":"https:\/\/elementor.com\/blog\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elementor.com\/blog\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elementor.com\/blog\/es\/#organization","name":"Elementor","url":"https:\/\/elementor.com\/blog\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elementor.com\/blog\/es\/#\/schema\/logo\/image\/","url":"https:\/\/elementor.com\/blog\/wp-content\/uploads\/2025\/06\/images.png","contentUrl":"https:\/\/elementor.com\/blog\/wp-content\/uploads\/2025\/06\/images.png","width":225,"height":225,"caption":"Elementor"},"image":{"@id":"https:\/\/elementor.com\/blog\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elemntor\/","https:\/\/x.com\/elemntor","https:\/\/www.instagram.com\/elementor\/","https:\/\/www.youtube.com\/channel\/UCt9kG_EDX8zwGSC1-ycJJVA?sub_confirmation=1","https:\/\/en.wikipedia.org\/wiki\/Elementor"]},{"@type":"Person","@id":"https:\/\/elementor.com\/blog\/es\/#\/schema\/person\/09f7425d5f0e4e8ac7764b202c165fc0","name":"Roi Tal","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/53a4b8103bf51815f66eec9532fb9ba89fb71bfb887c67660c39f06e73f509a5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/53a4b8103bf51815f66eec9532fb9ba89fb71bfb887c67660c39f06e73f509a5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53a4b8103bf51815f66eec9532fb9ba89fb71bfb887c67660c39f06e73f509a5?s=96&d=mm&r=g","caption":"Roi Tal"},"description":"Roi is a Product Marketing Manager at Elementor, working in the Editor Plugin team. He comes from a background of music and experience in content marketing and broadcasting, taking pride in creating meaningful communications that evoke and inspire. In his spare time, Roi enjoys making music, cooking, and watching movies.","url":"https:\/\/elementor.com\/blog\/es\/author\/roit\/"}]}},"_links":{"self":[{"href":"https:\/\/elementor.com\/blog\/es\/wp-json\/wp\/v2\/posts\/112021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elementor.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elementor.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elementor.com\/blog\/es\/wp-json\/wp\/v2\/users\/2024242"}],"replies":[{"embeddable":true,"href":"https:\/\/elementor.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=112021"}],"version-history":[{"count":0,"href":"https:\/\/elementor.com\/blog\/es\/wp-json\/wp\/v2\/posts\/112021\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elementor.com\/blog\/es\/wp-json\/wp\/v2\/media\/112022"}],"wp:attachment":[{"href":"https:\/\/elementor.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=112021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elementor.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=112021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elementor.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=112021"},{"taxonomy":"marketing_persona","embeddable":true,"href":"https:\/\/elementor.com\/blog\/es\/wp-json\/wp\/v2\/marketing_persona?post=112021"},{"taxonomy":"marketing_intent","embeddable":true,"href":"https:\/\/elementor.com\/blog\/es\/wp-json\/wp\/v2\/marketing_intent?post=112021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}